{"id":41006,"date":"2022-12-14T11:49:36","date_gmt":"2022-12-14T10:49:36","guid":{"rendered":"https:\/\/www.docenti.it\/blog\/?p=41006"},"modified":"2022-12-14T11:53:42","modified_gmt":"2022-12-14T10:53:42","slug":"organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione","status":"publish","type":"post","link":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/","title":{"rendered":"Organico docenti 2022\/24: le tabelle con i numeri per regione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sono uscite le tabelle con i numeri di posti disponibili per l&#8217;<strong>organico docenti 2022\/24<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Scopri tutti i numeri regione per regione.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Organico docenti 2022\/24: 620.256 posti<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il 5 dicembre \u00e8 stato registrato alla Corte dei Conti <strong>il decreto numero 272 del 17 ottobre 2022<\/strong> del Ministro dell\u2019Istruzione di concerto con il Ministro dell\u2019Economia e delle Finanze e con il Ministro per la Pubblica Amministrazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tale decreto contiene:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>i posti comuni; <\/li><li>i posti comuni di potenziamento; <\/li><li>e di sostegno per gli anni 2022\/24;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le consistenze delle dotazioni organiche per i posti: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>comuni; <\/li><li>nazionali; <\/li><li>e regionali del personale docente<br>di cui all\u2019articolo 1, comma 64, della legge 13 luglio 2015, n. 107, per l\u2019anno scolastico 2022\/2023, si trovano riportate nella <strong>Tabella A<\/strong>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le dotazioni organiche comprendono la variazione disposta ai sensi dell\u2019articolo 12, comma 1, del decreto legislativo 13 aprile 2017, n. 61, per l\u2019anno scolastico 2022\/2023, ovvero: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>291 posti<\/strong> (con un incremento di 441 posti per i docenti ITP e un decremento di 150 posti per docenti laureati). <br>Le dotazioni tengono altres\u00ec conto dei posti da destinare all\u2019educazione motoria nella scuola primaria per le classi quinte e dei posti da destinare alle classi costituite in deroga.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nella tabella trovi indicato anche il <strong>contingente dei posti comuni di potenziamento per l\u2019anno scolastico 2022\/23.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png\" alt=\"Organico Docenti\" class=\"wp-image-41029\" width=\"712\" height=\"359\"\/><figcaption>Photo credit: <em>Orizzonte Scuola<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sul sostegno sono presenti<strong> 11mila posti in pi\u00f9 per il corrente anno scolastico e<\/strong> <strong>9mila posti disponibili per il prossimo<\/strong>, secondo quanto previsto dalla legge di bilancio del 2021.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_5-1.png\" alt=\"Organico docenti\" class=\"wp-image-41030\"\/><figcaption>Photo credit: <em>Orizzonte Scuola<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nella Tabella C trovi il contingente dei posti per l\u2019adeguamento dell\u2019organico triennale alle situazioni di fatto.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E, visto che stiamo parlando dell&#8217;<strong>organico docenti<\/strong>, approfondiamo il tema e vediamo qualche curiosit\u00e0 a riguardo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Chi si occupa dell&#8217;organico scuola?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Come si forma l&#8217;organico scuola?<br>Chi se ne occupa?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 l&#8217;Ufficio Scolastico Regionale ad occuparsene e a stabilire l&#8217;<strong>organico&nbsp;di ogni provincia<\/strong>: sono poi gli Uffici Scolastici Provinciali che definiscono <strong>la distribuzione dei posti in ogni&nbsp;istituto.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma <em><strong>organico scuola<\/strong><\/em> \u00e8 un termine molto generico, al di sotto del quale ci sono varie sotto-categorie&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ad esempio: l&#8217;organico di diritto e l&#8217;organico dell&#8217;autonomia. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Che cos\u2019\u00e8 l&#8217;organico di diritto?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 l&#8217;ufficio Scolastico Provinciale a determinate, per ogni anno scolastico, l&#8217;<strong>organico di diritto<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa nomina viene fatta considerando il <strong>numero&nbsp;di&nbsp;classi autorizzate, sulla base del numero degli alunni iscritti.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vediamo, invece, che cos\u2019\u00e8 l&#8217;organico dell&#8217;autonomia. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come funziona l&#8217;organico dell&#8217;autonomia?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;organico dell&#8217;autonomia&nbsp;serve per realizzare&nbsp;l&#8217;offerta formativa scolastica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tutti i docenti devono contribuire alla sua piena attuazione<\/strong> e possono essere destinati all&#8217;organico in autonomia solo se sono in possesso dei titoli abilitanti e\/o delle necessarie competenze alle attivit\u00e0 di: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>insegnamento; <\/li><li>sostegno; <\/li><li>potenziamento; <\/li><li>attivit\u00e0 di coordinamento e organizzazione (se docenti di staff).&nbsp;<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Chi compone l&#8217;organico dell&#8217;autonomia?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;<strong>organico dell<\/strong>&#8216;<strong>autonomia<\/strong>, invece,&nbsp;\u00e8 disciplinato dall&#8217;art. 1 comma 63 della legge 107\/15 ed \u00e8 costituito da: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>posti comuni; <\/li><li>dai posti di sostegno;<\/li><li>e dai posti per il potenziamento.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Leggi le ultime notizie del blog:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.docenti.it\/blog\/messa-a-disposizione-come-le-scuole-controllano-lassegnazione-delle-supplenze\/\">Messa a Disposizione: come le scuole controllano l\u2019assegnazione delle supplenze<\/a><\/li><li><a href=\"https:\/\/www.docenti.it\/blog\/supplenze-da-mad-scavalcati-docenti-da-graduatorie-di-istituto-perche-succede\/\">Supplenze da MAD, scavalcati docenti da Graduatorie di Istituto: perch\u00e9 succede?<\/a><\/li><li><a href=\"https:\/\/www.docenti.it\/blog\/messa-a-disposizione-puoi-ancora-ottenere-una-supplenza-per-gennaio\/\">Messa a Disposizione: puoi ancora ottenere una supplenza per gennaio\u2026<\/a><\/li><li><a href=\"https:\/\/www.docenti.it\/blog\/concorsi-scuola-2023-i-nuovi-bandi-in-uscita\/\">Concorsi scuola 2023: i nuovi bandi in uscita<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Photo credit:&nbsp;<a href=\"https:\/\/pixabay.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">pixabay.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono uscite le tabelle con i numeri di posti disponibili per l&#8217;organico docenti 2022\/24. [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[63],"class_list":["post-41006","post","type-post","status-publish","format-standard","hentry","category-news","tag-diventare-insegnante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Organico docenti 2022\/24: le tabelle con i numeri per regione<\/title>\n<meta name=\"description\" content=\"Sono uscite le tabelle con i numeri di posti disponibili per l&#039;organico docenti 2022\/24. Scopri tutti i numeri regione per regione!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organico docenti 2022\/24: le tabelle con i numeri per regione\" \/>\n<meta property=\"og:description\" content=\"Sono uscite le tabelle con i numeri di posti disponibili per l&#039;organico docenti 2022\/24. Scopri tutti i numeri regione per regione!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog | Docenti.it\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/docenti.it\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=1555867670\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T10:49:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T10:53:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png\" \/>\n<meta name=\"author\" content=\"Martina Vaggi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Vaggi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/\"},\"author\":{\"name\":\"Martina Vaggi\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#\\\/schema\\\/person\\\/99c2fdaf54e96829fe4ed44da8233688\"},\"headline\":\"Organico docenti 2022\\\/24: le tabelle con i numeri per regione\",\"datePublished\":\"2022-12-14T10:49:36+00:00\",\"dateModified\":\"2022-12-14T10:53:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/\"},\"wordCount\":543,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Screenshot_4-2-1024x517.png\",\"keywords\":[\"diventare insegnante\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/\",\"url\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/\",\"name\":\"Organico docenti 2022\\\/24: le tabelle con i numeri per regione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Screenshot_4-2-1024x517.png\",\"datePublished\":\"2022-12-14T10:49:36+00:00\",\"dateModified\":\"2022-12-14T10:53:42+00:00\",\"description\":\"Sono uscite le tabelle con i numeri di posti disponibili per l'organico docenti 2022\\\/24. Scopri tutti i numeri regione per regione!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Screenshot_4-2-1024x517.png\",\"contentUrl\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Screenshot_4-2-1024x517.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Organico docenti 2022\\\/24: le tabelle con i numeri per regione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/\",\"name\":\"Blog | Docenti.it\",\"description\":\"Tutte le notizie e gli aggiornamenti dal mondo della scuola\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#organization\",\"name\":\"Blog | Docenti.it\",\"url\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fb_mad_img.png\",\"contentUrl\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fb_mad_img.png\",\"width\":1140,\"height\":620,\"caption\":\"Blog | Docenti.it\"},\"image\":{\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/docenti.it\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/#\\\/schema\\\/person\\\/99c2fdaf54e96829fe4ed44da8233688\",\"name\":\"Martina Vaggi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0015a6eaf31b83b6854be2b9017ba3dfbc26e1ae2e5ad121ac25778e214694ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0015a6eaf31b83b6854be2b9017ba3dfbc26e1ae2e5ad121ac25778e214694ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0015a6eaf31b83b6854be2b9017ba3dfbc26e1ae2e5ad121ac25778e214694ce?s=96&d=mm&r=g\",\"caption\":\"Martina Vaggi\"},\"description\":\"Classe 1991, copywriter e scrittrice. Nata a Sale, un paesino in provincia di Alessandria. Scrive dall\u2019et\u00e0 di 10 anni. Nel 2015 si laurea in Lettere Moderne presso l\u2019universit\u00e0 di Pavia. Nel 2020 pubblica il suo primo libro \\\"Il diario del silenzio - Storie reali di quarantena\\\" che descrive il processo di cambiamento della vita di 40 persone ai tempi del Covid. Nel 2022 si trasferisce a San Marino per lavorare come copywriter per Docenti.it\",\"sameAs\":[\"https:\\\/\\\/pensierisurrealidigentecomune.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=1555867670\",\"https:\\\/\\\/www.instagram.com\\\/martiggi91\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/in\\\/martina-vaggi\",\"https:\\\/\\\/www.youtube.com\\\/results?search_query=martina+vaggi\"],\"url\":\"https:\\\/\\\/www.docenti.it\\\/blog\\\/author\\\/martina-vaggi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organico docenti 2022\/24: le tabelle con i numeri per regione","description":"Sono uscite le tabelle con i numeri di posti disponibili per l'organico docenti 2022\/24. Scopri tutti i numeri regione per regione!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/","og_locale":"it_IT","og_type":"article","og_title":"Organico docenti 2022\/24: le tabelle con i numeri per regione","og_description":"Sono uscite le tabelle con i numeri di posti disponibili per l'organico docenti 2022\/24. Scopri tutti i numeri regione per regione!","og_url":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/","og_site_name":"Blog | Docenti.it","article_publisher":"https:\/\/www.facebook.com\/docenti.it","article_author":"https:\/\/www.facebook.com\/profile.php?id=1555867670","article_published_time":"2022-12-14T10:49:36+00:00","article_modified_time":"2022-12-14T10:53:42+00:00","og_image":[{"url":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png","type":"","width":"","height":""}],"author":"Martina Vaggi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Martina Vaggi","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#article","isPartOf":{"@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/"},"author":{"name":"Martina Vaggi","@id":"https:\/\/www.docenti.it\/blog\/#\/schema\/person\/99c2fdaf54e96829fe4ed44da8233688"},"headline":"Organico docenti 2022\/24: le tabelle con i numeri per regione","datePublished":"2022-12-14T10:49:36+00:00","dateModified":"2022-12-14T10:53:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/"},"wordCount":543,"commentCount":0,"publisher":{"@id":"https:\/\/www.docenti.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png","keywords":["diventare insegnante"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/","url":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/","name":"Organico docenti 2022\/24: le tabelle con i numeri per regione","isPartOf":{"@id":"https:\/\/www.docenti.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#primaryimage"},"image":{"@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png","datePublished":"2022-12-14T10:49:36+00:00","dateModified":"2022-12-14T10:53:42+00:00","description":"Sono uscite le tabelle con i numeri di posti disponibili per l'organico docenti 2022\/24. Scopri tutti i numeri regione per regione!","breadcrumb":{"@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#primaryimage","url":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png","contentUrl":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2022\/12\/Screenshot_4-2-1024x517.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.docenti.it\/blog\/organico-docenti-2022-24-le-tabelle-con-i-numeri-per-regione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.docenti.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Organico docenti 2022\/24: le tabelle con i numeri per regione"}]},{"@type":"WebSite","@id":"https:\/\/www.docenti.it\/blog\/#website","url":"https:\/\/www.docenti.it\/blog\/","name":"Blog | Docenti.it","description":"Tutte le notizie e gli aggiornamenti dal mondo della scuola","publisher":{"@id":"https:\/\/www.docenti.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.docenti.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.docenti.it\/blog\/#organization","name":"Blog | Docenti.it","url":"https:\/\/www.docenti.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.docenti.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2025\/06\/fb_mad_img.png","contentUrl":"https:\/\/www.docenti.it\/blog\/wp-content\/uploads\/2025\/06\/fb_mad_img.png","width":1140,"height":620,"caption":"Blog | Docenti.it"},"image":{"@id":"https:\/\/www.docenti.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/docenti.it"]},{"@type":"Person","@id":"https:\/\/www.docenti.it\/blog\/#\/schema\/person\/99c2fdaf54e96829fe4ed44da8233688","name":"Martina Vaggi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0015a6eaf31b83b6854be2b9017ba3dfbc26e1ae2e5ad121ac25778e214694ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0015a6eaf31b83b6854be2b9017ba3dfbc26e1ae2e5ad121ac25778e214694ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0015a6eaf31b83b6854be2b9017ba3dfbc26e1ae2e5ad121ac25778e214694ce?s=96&d=mm&r=g","caption":"Martina Vaggi"},"description":"Classe 1991, copywriter e scrittrice. Nata a Sale, un paesino in provincia di Alessandria. Scrive dall\u2019et\u00e0 di 10 anni. Nel 2015 si laurea in Lettere Moderne presso l\u2019universit\u00e0 di Pavia. Nel 2020 pubblica il suo primo libro \"Il diario del silenzio - Storie reali di quarantena\" che descrive il processo di cambiamento della vita di 40 persone ai tempi del Covid. Nel 2022 si trasferisce a San Marino per lavorare come copywriter per Docenti.it","sameAs":["https:\/\/pensierisurrealidigentecomune.com\/","https:\/\/www.facebook.com\/profile.php?id=1555867670","https:\/\/www.instagram.com\/martiggi91\/","https:\/\/it.linkedin.com\/in\/martina-vaggi","https:\/\/www.youtube.com\/results?search_query=martina+vaggi"],"url":"https:\/\/www.docenti.it\/blog\/author\/martina-vaggi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/posts\/41006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/comments?post=41006"}],"version-history":[{"count":0,"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/posts\/41006\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/media?parent=41006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/categories?post=41006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.docenti.it\/blog\/wp-json\/wp\/v2\/tags?post=41006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}